{"id":18,"date":"2026-03-06T23:23:10","date_gmt":"2026-03-06T23:23:10","guid":{"rendered":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/?page_id=18"},"modified":"2026-03-06T23:23:10","modified_gmt":"2026-03-06T23:23:10","slug":"icerik-ekle","status":"publish","type":"page","link":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/icerik-ekle\/","title":{"rendered":"\u0130\u00e7erik ekle"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-18","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0130\u00e7erik ekle - Biriz SEO Control Center<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/icerik-ekle\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0130\u00e7erik ekle - Biriz SEO Control Center\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/icerik-ekle\/\" \/>\n<meta property=\"og:site_name\" content=\"Biriz SEO Control Center\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/icerik-ekle\\\/\",\"url\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/icerik-ekle\\\/\",\"name\":\"\u0130\u00e7erik ekle - Biriz SEO Control Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/#website\"},\"datePublished\":\"2026-03-06T23:23:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/icerik-ekle\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/icerik-ekle\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/icerik-ekle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0130\u00e7erik ekle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/#website\",\"url\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/\",\"name\":\"Biriz SEO Control Center\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/#organization\",\"name\":\"Biriz SEO Control Center\",\"url\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/biriz_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/biriz_logo.jpg\",\"width\":400,\"height\":400,\"caption\":\"Biriz SEO Control Center\"},\"image\":{\"@id\":\"https:\\\/\\\/seopanel.biriz.tr\\\/seopanelbiriz\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0130\u00e7erik ekle - Biriz SEO Control Center","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/icerik-ekle\/","og_locale":"tr_TR","og_type":"article","og_title":"\u0130\u00e7erik ekle - Biriz SEO Control Center","og_url":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/icerik-ekle\/","og_site_name":"Biriz SEO Control Center","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/icerik-ekle\/","url":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/icerik-ekle\/","name":"\u0130\u00e7erik ekle - Biriz SEO Control Center","isPartOf":{"@id":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/#website"},"datePublished":"2026-03-06T23:23:10+00:00","breadcrumb":{"@id":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/icerik-ekle\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seopanel.biriz.tr\/seopanelbiriz\/icerik-ekle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/icerik-ekle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/"},{"@type":"ListItem","position":2,"name":"\u0130\u00e7erik ekle"}]},{"@type":"WebSite","@id":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/#website","url":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/","name":"Biriz SEO Control Center","description":"","publisher":{"@id":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/#organization","name":"Biriz SEO Control Center","url":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/#\/schema\/logo\/image\/","url":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/wp-content\/uploads\/2026\/03\/biriz_logo.jpg","contentUrl":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/wp-content\/uploads\/2026\/03\/biriz_logo.jpg","width":400,"height":400,"caption":"Biriz SEO Control Center"},"image":{"@id":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/#\/schema\/logo\/image\/"}}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":1,"href":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"predecessor-version":[{"id":19,"href":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/wp-json\/wp\/v2\/pages\/18\/revisions\/19"}],"wp:attachment":[{"href":"https:\/\/seopanel.biriz.tr\/seopanelbiriz\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}